{"id":9571,"date":"2025-07-04T12:27:45","date_gmt":"2025-07-04T10:27:45","guid":{"rendered":"https:\/\/starlight.rocks\/?page_id=9571"},"modified":"2025-07-04T12:27:45","modified_gmt":"2025-07-04T10:27:45","slug":"bruce-dickinson","status":"publish","type":"page","link":"https:\/\/starlight.rocks\/en\/bruce-dickinson\/","title":{"rendered":"Bruce Dickinson"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><div class=\"vc_row row wpb_row jt_row vc_row row-fluid jt_row-fluid\"><div class=\"wpb_column jt_col vc_column_container vc_col-sm-12 col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"voffset70\"><\/div><div class=\"separator-icon\">\n              <i class=\"vc-oi vc-oi-mic\"><\/i>\n            <\/div><div class=\"voffset30\"><\/div><p class=\"pretitle\">News, music and concerts<\/p><div class=\"voffset20\"><\/div>\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<h2 class=\"title\">Bruce Dickinson<\/h2>\n\n\t\t<\/div>\n\t<\/div>\n<div class=\"voffset30\"><\/div>\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p style=\"text-align: center;\">Bruce Dickinson is a musician and known as the frontman of the internationally renowned metal band Iron Maiden.<\/p>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div><div class=\"vc_row row wpb_row jt_row vc_row row-fluid jt_row-fluid\"><div class=\"wpb_column jt_col vc_column_container vc_col-sm-12 col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n<div class=\"vc_grid-container-wrapper vc_clearfix vc_grid-animation-zoomIn\">\n\t<div class=\"vc_grid-container vc_clearfix wpb_content_element vc_masonry_grid\" data-initial-loading-animation=\"zoomIn\" data-vc-grid-settings=\"{&quot;page_id&quot;:9571,&quot;style&quot;:&quot;all-masonry&quot;,&quot;action&quot;:&quot;vc_get_vc_grid_data&quot;,&quot;shortcode_id&quot;:&quot;1751624772556-28a1a883-b4a6-6&quot;,&quot;tag&quot;:&quot;vc_masonry_grid&quot;}\" data-vc-request=\"https:\/\/starlight.rocks\/wp-admin\/admin-ajax.php\" data-vc-post-id=\"9571\" data-vc-public-nonce=\"c5f124dce6\">\n\t\t\n\t<\/div>\n<\/div><\/div><\/div><\/div><\/div><div data-vc-full-width=\"true\" data-vc-full-width-temp=\"true\" data-vc-full-width-init=\"false\" class=\"vc_row row wpb_row jt_row vc_row row-fluid jt_row-fluid vc_custom_1685094001879 vc_row row-has-fill\"><div class=\"wpb_column jt_col vc_column_container vc_col-sm-12 col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"voffset70\"><\/div><div class=\"separator-icon\">\n              <i class=\"vc-oi vc-oi-mic\"><\/i>\n            <\/div><div class=\"voffset30\"><\/div><p class=\"pretitle\">Every voice counts<\/p><div class=\"voffset20\"><\/div><h2 class=\"title\">contact<\/h2><div class=\"voffset80\"><\/div><div class=\"vc_row row wpb_row jt_row vc_inner vc_row row-fluid jt_row-fluid\"><div class=\"wpb_column jt_col vc_column_container vc_col-sm-12 col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p style=\"text-align: center;\"><span style=\"color: #ffffff;\">Are you a band, record label or PR agency looking for a magazine that writes about you or works with you? Then you've come to the right place. Send us an email via our contact form and get in touch with us directly and easily. We look forward to hearing from you!<\/span><\/p>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div><div class=\"vc_row row wpb_row jt_row vc_inner vc_row row-fluid jt_row-fluid\"><div class=\"wpb_column jt_col vc_column_container vc_col-sm-6 col-sm-6\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><form action=\"https:\/\/starlight.rocks\/wp-content\/plugins\/muziq-jellythemes-plugin\/mail.php\" method=\"post\" id=\"contactform\" class=\"contact-form\" data-trp-original-action=\"https:\/\/starlight.rocks\/wp-content\/plugins\/muziq-jellythemes-plugin\/mail.php\">\n              <div class=\"form-group\">\n                <label class=\"title small\" for=\"name\">Your name::<\/label>\n                <input type=\"text\" placeholder=\"Name\" name=\"name\" id=\"name\" class=\"text name required\" required>\n              <\/div>\n\n              <div class=\"form-group\">\n                <label class=\"title small\" for=\"email\">Your email:<\/label>\n                <input type=\"email\" placeholder=\"Email\" name=\"email\" id=\"email\" class=\"text email required\" required>\n              <\/div>\n\n              <div class=\"form-group\">\n                <label class=\"title small\" for=\"message\">Your message:<\/label>\n                <textarea name=\"message\" class=\"text area required\" id=\"message\" placeholder=\"Type message\" required><\/textarea>\n              <\/div>\n              <p class=\"hide send-success\">Your message have been sent<\/p>\n              <input type=\"submit\" value=\"Submit\" class=\"btn rounded\">\n              <div class=\"voffset80\"><\/div>\n            <input type=\"hidden\" name=\"trp-form-language\" value=\"en\"\/><\/form>\n\n            <\/div><\/div><\/div><div class=\"wpb_column jt_col vc_column_container vc_col-sm-6 col-sm-6\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"col-contact\">\n\t              <h4 class=\"title small\">Starlight.rocks | Music Magazine<\/h4>\n\t              <div class=\"voffset20\"><\/div>\n\t              <p><span style=\"color: #ffffff;\">Hockenbroicherstrasse 11,<\/span><br \/>\n<span style=\"color: #ffffff;\">53881 Euskirchen, DE<\/span><\/p>\n\n\t              <ul class=\"contact\">\n\t                <li><i class=\"fa fa-phone\"><\/i>+49 (0)2255 308 91 81<\/li>\n\t                <li><i class=\"fa fa-envelope\"><\/i> info@starlight.rocks<\/li>\n\t              <\/ul>\n\t              <h4 class=\"title small\">Get socialized with us<\/h4>\n\t              <ul class=\"social-links\"><li><a href=\"https:\/\/www.facebook.com\/starlight.dot.rocks\" target=\"_blank\" rel=\"noopener\"><i class=\"fa fa-facebook\"><\/i><\/a><\/li><li><a href=\"https:\/\/twitter.com\/starlight_rocks\" target=\"_blank\" rel=\"noopener\"><i class=\"fa fa-twitter\"><\/i><\/a><\/li><li><a href=\"#\"><i class=\"fa fa-google-plus\"><\/i><\/a><\/li><li><a href=\"https:\/\/www.linkedin.com\/in\/lila-rockwood\/\" target=\"_blank\" rel=\"noopener\"><i class=\"fa fa-linkedin\"><\/i><\/a><\/li><li><a href=\"#\"><i class=\"fa fa-pinterest\"><\/i><\/a><\/li><\/ul><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"vc_row-full-width vc_clearfix\"><\/div>\n<\/div>","protected":false},"excerpt":{"rendered":"Latest news, music and concerts Bruce Dickinson Bruce Dickinson is a musician and best known as the frontman of the internationally renowned metal band Iron Maiden. Every voice countsContact Are you a band, record label or PR agency looking for a magazine to write about you or work with you? Then you've come to the right place. Write us a [...]","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"multipage.php","meta":{"footnotes":""},"categories":[28],"tags":[],"class_list":["post-9571","page","type-page","status-publish","hentry","category-a-kews-tag"],"_links":{"self":[{"href":"https:\/\/starlight.rocks\/en\/wp-json\/wp\/v2\/pages\/9571","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/starlight.rocks\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/starlight.rocks\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/starlight.rocks\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/starlight.rocks\/en\/wp-json\/wp\/v2\/comments?post=9571"}],"version-history":[{"count":1,"href":"https:\/\/starlight.rocks\/en\/wp-json\/wp\/v2\/pages\/9571\/revisions"}],"predecessor-version":[{"id":9572,"href":"https:\/\/starlight.rocks\/en\/wp-json\/wp\/v2\/pages\/9571\/revisions\/9572"}],"wp:attachment":[{"href":"https:\/\/starlight.rocks\/en\/wp-json\/wp\/v2\/media?parent=9571"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/starlight.rocks\/en\/wp-json\/wp\/v2\/categories?post=9571"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/starlight.rocks\/en\/wp-json\/wp\/v2\/tags?post=9571"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}